{"id":77296,"date":"2026-04-20T07:17:15","date_gmt":"2026-04-20T11:47:15","guid":{"rendered":"https:\/\/elmundodelosnegocios.com.do\/v1\/?p=77296"},"modified":"2026-04-20T07:17:17","modified_gmt":"2026-04-20T11:47:17","slug":"presidente-abinader-entrega-144-apartamentos-financia-banreservas","status":"publish","type":"post","link":"https:\/\/elmundodelosnegocios.com.do\/v1\/presidente-abinader-entrega-144-apartamentos-financia-banreservas\/","title":{"rendered":"Presidente Abinader entrega 144 apartamentos financia Banreservas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Santo Domingo.\u2013<\/strong>&nbsp;Banreservas financi\u00f3 la adquisici\u00f3n de 144 apartamentos correspondientes a la primera etapa del Residencial Laderas del Este, los cuales fueron entregados por el presidente de la Rep\u00fablica, Luis Abinader, a igual n\u00famero de familias.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a570b350366b&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a570b350366b\" class=\"aligncenter size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/elmundodelosnegocios.com.do\/v1\/wp-content\/uploads\/2026\/04\/Foto-01-1-1024x682.jpeg\" alt=\"El presidente Luis Abinader, acompa\u00f1ado por el ministro de la Vivienda y Edificaciones, V\u00edctor Bison\u00f3; y el presidente ejecutivo de Banreservas, doctor Leonardo Aguilera, entrega la llave de un apartamento a Rosa Pe\u00f1a M\u00e9ndez y su familia en el Residencial Laderas del Este. Les acompa\u00f1an Lucrecia Santana Leyba, gobernadora provincial de Santo Domingo; Francisco C\u00e9sar Rojas, alcalde del municipio de San Antonio de Guerra; y miembros de la constructora Fasa.\" class=\"wp-image-77297\" srcset=\"https:\/\/elmundodelosnegocios.com.do\/v1\/wp-content\/uploads\/2026\/04\/Foto-01-1-1024x682.jpeg 1024w, https:\/\/elmundodelosnegocios.com.do\/v1\/wp-content\/uploads\/2026\/04\/Foto-01-1-300x200.jpeg 300w, https:\/\/elmundodelosnegocios.com.do\/v1\/wp-content\/uploads\/2026\/04\/Foto-01-1-768x512.jpeg 768w, https:\/\/elmundodelosnegocios.com.do\/v1\/wp-content\/uploads\/2026\/04\/Foto-01-1.jpeg 1100w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">El presidente Luis Abinader, acompa\u00f1ado por el ministro de la Vivienda y Edificaciones, V\u00edctor Bison\u00f3; y el presidente ejecutivo de Banreservas, doctor Leonardo Aguilera, entrega la llave de un apartamento a Rosa Pe\u00f1a M\u00e9ndez y su familia en el Residencial Laderas del Este. Les acompa\u00f1an Lucrecia Santana Leyba, gobernadora provincial de Santo Domingo; Francisco C\u00e9sar Rojas, alcalde del municipio de San Antonio de Guerra; y miembros de la constructora Fasa.<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Durante la actividad, el mandatario valor\u00f3 el impacto de estos proyectos en la calidad de vida de la poblaci\u00f3n y destac\u00f3 el \u00e9xito de la colaboraci\u00f3n entre los sectores&nbsp;p\u00fablico y privado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHa sido un verdadero \u00e9xito de una alianza p\u00fablico-privada que ha permitido que miles de dominicanos tengan su vivienda\u201d, expres\u00f3 Abinader.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente ejecutivo de Banreservas, doctor Leonardo Aguilera, inform\u00f3&nbsp;durante el acto en el municipio de San Antonio Guerra que la entidad ha dispuesto financiamiento superior a RD$330 millones, con una tasa de inter\u00e9s fija del 8%&nbsp;a siete a\u00f1os, en condiciones favorables.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a570b3503b99&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a570b3503b99\" class=\"aligncenter size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/elmundodelosnegocios.com.do\/v1\/wp-content\/uploads\/2026\/04\/Foto-02-1-1024x683.jpeg\" alt=\"El presidente Luis Abinader, junto al ministro de la Vivienda y Edificaciones, V\u00edctor Bison\u00f3; y el presidente ejecutivo de Banreservas, el doctor Leonardo Aguilera, entrega la llave de un apartamento a Eugenia Soriano y su familia, en el Residencial Laderas del Este. Les acompa\u00f1an Lucrecia Santana, gobernadora provincial de Santo Domingo; el alcalde Francisco C\u00e9sar Rojas; y representantes de la constructora Fasa.\" class=\"wp-image-77298\" srcset=\"https:\/\/elmundodelosnegocios.com.do\/v1\/wp-content\/uploads\/2026\/04\/Foto-02-1-1024x683.jpeg 1024w, https:\/\/elmundodelosnegocios.com.do\/v1\/wp-content\/uploads\/2026\/04\/Foto-02-1-300x200.jpeg 300w, https:\/\/elmundodelosnegocios.com.do\/v1\/wp-content\/uploads\/2026\/04\/Foto-02-1-768x512.jpeg 768w, https:\/\/elmundodelosnegocios.com.do\/v1\/wp-content\/uploads\/2026\/04\/Foto-02-1-1536x1024.jpeg 1536w, https:\/\/elmundodelosnegocios.com.do\/v1\/wp-content\/uploads\/2026\/04\/Foto-02-1-2048x1365.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">El presidente Luis Abinader, junto al ministro de la Vivienda y Edificaciones, V\u00edctor Bison\u00f3; y el presidente ejecutivo de Banreservas, el doctor Leonardo Aguilera, entrega la llave de un apartamento a Eugenia Soriano y su familia, en el Residencial Laderas del Este. Les acompa\u00f1an Lucrecia Santana, gobernadora provincial de Santo Domingo; el alcalde Francisco C\u00e9sar Rojas; y representantes de la constructora Fasa.<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">\u201cHoy, al entregar las llaves de sus nuevos apartamentos a 144 de las 368 familias que ocupar\u00e1n este moderno residencial, no solo cumplimos con una meta del presidente, sino que tambi\u00e9n damos respuesta a una necesidad leg\u00edtima de los dominicanos que aspiran a un techo digno, con las comodidades que ofrece este proyecto\u201d, dijo el ejecutivo.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a570b3503f36&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a570b3503f36\" class=\"aligncenter size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/elmundodelosnegocios.com.do\/v1\/wp-content\/uploads\/2026\/04\/Foto-03-1024x682.jpeg\" alt=\"\" class=\"wp-image-77299\" srcset=\"https:\/\/elmundodelosnegocios.com.do\/v1\/wp-content\/uploads\/2026\/04\/Foto-03-1024x682.jpeg 1024w, https:\/\/elmundodelosnegocios.com.do\/v1\/wp-content\/uploads\/2026\/04\/Foto-03-300x200.jpeg 300w, https:\/\/elmundodelosnegocios.com.do\/v1\/wp-content\/uploads\/2026\/04\/Foto-03-768x512.jpeg 768w, https:\/\/elmundodelosnegocios.com.do\/v1\/wp-content\/uploads\/2026\/04\/Foto-03.jpeg 1100w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">El presidente ejecutivo de Banreservas, doctor Leonardo Aguilera, habla durante la entrega de 144 unidades del Residencial Laderas del Este, del Programa Familia Feliz.<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Aguilera destac\u00f3 que cada unidad habitacional ha sido concebida para brindar seguridad y bienestar, y&nbsp;reafirm\u00f3 que el hogar constituye el primer espacio donde se construyen valores y se proyecta el futuro de la naci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, se\u00f1al\u00f3 que esta entrega forma parte de una pol\u00edtica de soluciones habitacionales que ha permitido a miles de dominicanos acceder a una vivienda propia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El proyecto Laderas del Este contempla un total de 368 unidades habitacionales, de las cuales,&nbsp;en esta etapa,&nbsp;144 familias comienzan a disfrutar de las amenidades del complejo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta iniciativa es el resultado de una alianza entre Banreservas, el Ministerio de Vivienda y Edificaciones y el sector privado, con el objetivo de ampliar el acceso a soluciones habitacionales en el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el acto participaron autoridades legislativas, municipales y provinciales, as\u00ed como ejecutivos de la empresa constructora y de Banreservas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo.\u2013&nbsp;Banreservas financi\u00f3 la adquisici\u00f3n de 144 apartamentos correspondientes a la primera etapa del Residencial Laderas del Este, los cuales fueron entregados por el presidente de la Rep\u00fablica, Luis Abinader,&hellip; <\/p>\n","protected":false},"author":2,"featured_media":77301,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"https:\/\/elmundodelosnegocios.com.do\/v1\/wp-content\/uploads\/2026\/04\/Foto-01-1.jpeg","fifu_image_alt":"","footnotes":""},"categories":[69],"tags":[],"class_list":["post-77296","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-construccion"],"_links":{"self":[{"href":"https:\/\/elmundodelosnegocios.com.do\/v1\/wp-json\/wp\/v2\/posts\/77296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elmundodelosnegocios.com.do\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elmundodelosnegocios.com.do\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elmundodelosnegocios.com.do\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elmundodelosnegocios.com.do\/v1\/wp-json\/wp\/v2\/comments?post=77296"}],"version-history":[{"count":1,"href":"https:\/\/elmundodelosnegocios.com.do\/v1\/wp-json\/wp\/v2\/posts\/77296\/revisions"}],"predecessor-version":[{"id":77300,"href":"https:\/\/elmundodelosnegocios.com.do\/v1\/wp-json\/wp\/v2\/posts\/77296\/revisions\/77300"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elmundodelosnegocios.com.do\/v1\/wp-json\/wp\/v2\/media\/77301"}],"wp:attachment":[{"href":"https:\/\/elmundodelosnegocios.com.do\/v1\/wp-json\/wp\/v2\/media?parent=77296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elmundodelosnegocios.com.do\/v1\/wp-json\/wp\/v2\/categories?post=77296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elmundodelosnegocios.com.do\/v1\/wp-json\/wp\/v2\/tags?post=77296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}